{"id":25232,"date":"2024-11-11T13:26:09","date_gmt":"2024-11-11T16:26:09","guid":{"rendered":"https:\/\/coreto.cl\/home\/?p=25232"},"modified":"2024-11-11T21:48:33","modified_gmt":"2024-11-12T00:48:33","slug":"coreto-y-circopolis-en-filsa-2024","status":"publish","type":"post","link":"https:\/\/coreto.cl\/home\/coreto-y-circopolis-en-filsa-2024\/","title":{"rendered":"Coreto y Circopolis en FILSA 2024"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25232\" class=\"elementor elementor-25232\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aba9b0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aba9b0a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12d63142\" data-id=\"12d63142\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dc4634e elementor-widget elementor-widget-text-editor\" data-id=\"7dc4634e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4 class=\"p1\" style=\"text-align: left;\">\u00abDomingo 10 de Noviembre: Un d\u00eda inolvidable en la FILSA 2024\u00bb<\/h4>\n<p class=\"p1\">La emoci\u00f3n y la magia llenaron el aire en la Feria Internacional del Libro de Santiago, FILSA 2024, gracias a la invitaci\u00f3n de la Fundaci\u00f3n Museo del Circo Nacional. Nuestro Circo Social \u00abCircopolis\u00bb de Lo Espejo tuvo el honor de presentar un espect\u00e1culo impresionante, fruto del trabajo creativo y colectivo de nuestros participantes y familias.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Con la m\u00fasica envolvente de la talentosa Pascuala Ilabaca, nuestros artistas tomaron el escenario por asalto:<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; Las intr\u00e9pidas Mar\u00eda Jos\u00e9, Tiare, Kenia y Paulette nos hipnotizaron con su Ula-Ula.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; El maestro Martin nos dej\u00f3 boquiabiertos con su Plato Chino.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; La acrobacia grupal de Antonella, Julieta, Naiara, Elo\u00edsa, Mia y Agatha, junto a Bryan, nos tom\u00f3 la respiraci\u00f3n.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; Fabian y Sebasti\u00e1n nos maravillaron con su Di\u00e1bolo.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; Antonella nos regal\u00f3 una creaci\u00f3n Ula-Ula individual inolvidable.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; Emilio nos demostr\u00f3 su habilidad con Malabares con Pelotas.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">&#8211; Y los payasos Semillita (Franco) y Queso (Agust\u00edn) nos llenaron de risas.<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Fue un momento m\u00e1gico, con nuestras familias en el p\u00fablico, compartiendo la emoci\u00f3n y el orgullo de nuestro trabajo. En la Escuela de Circo Social, creemos firmemente que el arte es un poderoso instrumento de transformaci\u00f3n social. \u00a1Gracias FILSA 2024 por esta oportunidad \u00fanica!<\/p>\n<h4 class=\"p1\" style=\"margin-bottom: 0px; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-size-adjust: none; font-kerning: auto; font-optical-sizing: auto; font-feature-settings: normal; font-variation-settings: normal; font-variant-position: normal; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Helvetica; color: #000000; text-align: start;\">\u00a0<\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70123b8 elementor-widget elementor-widget-image\" data-id=\"70123b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25233\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/06bdf61b-f4ec-4768-9fc5-26786e2ae863.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95ca13c elementor-widget elementor-widget-image\" data-id=\"95ca13c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25234\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/832cb495-252d-4896-ade0-c1fba7734310.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87ef801 elementor-widget elementor-widget-image\" data-id=\"87ef801\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"1600\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813.jpeg\" class=\"attachment-large size-large wp-image-25237\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813.jpeg 900w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813-300x533.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813-163x290.jpeg 163w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813-768x1365.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/aed249be-11be-4fef-9cae-b719f4167813-864x1536.jpeg 864w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a18dbad elementor-widget elementor-widget-image\" data-id=\"a18dbad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25236\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/7937aa0f-a323-4859-95d8-a1c2e66fe3f0.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e5e963 elementor-widget elementor-widget-image\" data-id=\"8e5e963\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25235\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/2294ca2f-5895-40d4-848d-d4b0462f475b.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4a3af6 elementor-widget elementor-widget-image\" data-id=\"f4a3af6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25239\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/e7af580b-744a-4e89-9497-4623396c2a89.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98ae1c9 elementor-widget elementor-widget-image\" data-id=\"98ae1c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1600\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1.jpeg\" class=\"attachment-large size-large wp-image-25245\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1.jpeg 900w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1-300x533.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1-163x290.jpeg 163w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1-768x1365.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/ead19e81-8f21-4aef-ab86-7f08db82aef1-864x1536.jpeg 864w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c82c6a3 elementor-widget elementor-widget-image\" data-id=\"c82c6a3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1600\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9.jpeg\" class=\"attachment-large size-large wp-image-25246\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9.jpeg 900w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9-300x533.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9-163x290.jpeg 163w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9-768x1365.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/190261d8-dab1-4f1e-b110-f418ce0f9dc9-864x1536.jpeg 864w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a75051f elementor-widget elementor-widget-image\" data-id=\"a75051f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"619\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-1100x619.jpeg\" class=\"attachment-large size-large wp-image-25238\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-1100x619.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-300x169.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-440x248.jpeg 440w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-768x432.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874-1536x864.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/dd474a92-641c-44fd-937c-7948faca6874.jpeg 1600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda35bd elementor-widget elementor-widget-image\" data-id=\"fda35bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"825\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-1100x825.jpeg\" class=\"attachment-large size-large wp-image-25240\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-1100x825.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-300x225.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-387x290.jpeg 387w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-768x576.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-1536x1152.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0399-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb2bbc elementor-widget elementor-widget-image\" data-id=\"1cb2bbc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"825\" src=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-1100x825.jpeg\" class=\"attachment-large size-large wp-image-25241\" alt=\"\" srcset=\"https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-1100x825.jpeg 1100w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-300x225.jpeg 300w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-387x290.jpeg 387w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-768x576.jpeg 768w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-1536x1152.jpeg 1536w, https:\/\/coreto.cl\/home\/wp-content\/uploads\/2024\/11\/IMG_0407-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7526063 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7526063\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eea6c4b\" data-id=\"eea6c4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00abDomingo 10 de Noviembre: Un d\u00eda inolvidable en la FILSA 2024\u00bb La emoci\u00f3n y la magia llenaron el aire en la Feria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,559],"tags":[],"class_list":["post-25232","post","type-post","status-publish","format-standard","hentry","category-sin-cotegoria","category-noticias"],"_links":{"self":[{"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/posts\/25232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/comments?post=25232"}],"version-history":[{"count":27,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/posts\/25232\/revisions"}],"predecessor-version":[{"id":25270,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/posts\/25232\/revisions\/25270"}],"wp:attachment":[{"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/media?parent=25232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/categories?post=25232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coreto.cl\/home\/wp-json\/wp\/v2\/tags?post=25232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}